{"id":602130,"count":1,"description":"","link":"https:\/\/blog.ilgiornale.it\/franza\/tag\/museo-del-novecento-lato-via-marconi-milano\/","name":"Museo del Novecento lato Via Marconi- Milano","slug":"museo-del-novecento-lato-via-marconi-milano","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.ilgiornale.it\/franza\/wp-json\/wp\/v2\/tags\/602130"}],"collection":[{"href":"https:\/\/blog.ilgiornale.it\/franza\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.ilgiornale.it\/franza\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.ilgiornale.it\/franza\/wp-json\/wp\/v2\/posts?tags=602130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}