{"id":148,"date":"2009-12-21T16:00:39","date_gmt":"2009-12-21T15:00:39","guid":{"rendered":"https:\/\/blog.ilgiornale.it\/ruzzo\/2009\/12\/21\/da-amalfi-a-sorrento-la-maratona-coast-to-coast\/"},"modified":"2009-12-21T16:00:39","modified_gmt":"2009-12-21T15:00:39","slug":"da-amalfi-a-sorrento-la-maratona-coast-to-coast","status":"publish","type":"post","link":"https:\/\/blog.ilgiornale.it\/ruzzo\/2009\/12\/21\/da-amalfi-a-sorrento-la-maratona-coast-to-coast\/","title":{"rendered":"Da Amalfi a Sorrento, la maratona &#8220;coast to coast&#8221;"},"content":{"rendered":"<p>[photopress:sorrento.jpg,full,centered]Da Amalfi a Sorrento di corsa. Un&#8217;ottima occasione per rifarsi gli occhi con panorami mozzafiato, per scappare dal freddo siberiano che sta avvolgendo le regioni del nord e per smaltire qualche bagordo natalizio. Quella che prender\u00e0 il via domenica 27 dicembre sulla costiera amalfitana\u00a0\u00e8\u00a0la prima edizione di Coast to coast, la maratona promossa dalla Napoli Nord Marathon. Oltre alla Maratona di km 42,195, che si correr\u00e0 tra Minori, Atrani, Amalfi, Conca dei Marini, Furore, Praiano, Positano e, attraversando Vico Equense e Piano di Sorrento, si concluder\u00e0 a Sant\u2019Agnello, nel cuore della penisola sorrentina, sar\u00e0 organizzata una mini maratona, non competitiva, nei comuni attraversati dove i ragazzi e persone di ogni\u00a0 et\u00e0 potranno, tutti insieme, partecipare. Prevista la partecipazione di mille atleti, provenienti da federazioni italiane e estere \u00abAbbiamo promosso l\u2019evento &#8211; ha spiegato il presidente della provincia di Napoli Luigi Cesaro &#8211; perch\u00e8 crediamo, come ente,\u00a0 fermamente nello sport e nei giovani. Ma sono anche convinto che\u00a0 questa sia la strada da percorrere per il rilancio dei nostri territori e per accendere i riflettori su manifestazioni di pregio,\u00a0 che saranno ulteriormente incentivate, e che spingono anche il\u00a0 turismo, settore sul quale stiamo investendo grandi risorse\u00bb.<\/p>\n<p><a href=\"http:\/\/www.maratonacoasttocoast.com\/\">http:\/\/www.maratonacoasttocoast.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><p>[photopress:sorrento.jpg,full,centered]Da Amalfi a Sorrento di corsa. Un&#8217;ottima occasione per rifarsi gli occhi con panorami mozzafiato, per scappare dal freddo siberiano che sta avvolgendo le regioni del nord e per smaltire qualche bagordo natalizio. Quella che prender\u00e0 il via domenica 27 dicembre sulla costiera amalfitana\u00a0\u00e8\u00a0la prima edizione di Coast to coast, la maratona promossa dalla Napoli Nord Marathon. Oltre alla Maratona di km 42,195, che si correr\u00e0 tra Minori, Atrani, Amalfi, Conca dei Marini, Furore, Praiano, Positano e, attraversando Vico Equense e Piano di Sorrento, si concluder\u00e0 a Sant\u2019Agnello, nel cuore della penisola sorrentina, sar\u00e0 organizzata una mini maratona, non competitiva, [&hellip;]<\/p>\n&nbsp;&nbsp;<div class=\"readmore\"><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/2009\/12\/21\/da-amalfi-a-sorrento-la-maratona-coast-to-coast\/\">Continua a leggere...<\/a><\/div><\/p>","protected":false},"author":956,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/148"}],"collection":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/users\/956"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":0,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}