{"id":149,"date":"2009-12-23T15:06:48","date_gmt":"2009-12-23T14:06:48","guid":{"rendered":"https:\/\/blog.ilgiornale.it\/ruzzo\/2009\/12\/23\/maratoneti-e-non-e-tempo-di-auguri\/"},"modified":"2009-12-23T23:39:18","modified_gmt":"2009-12-23T22:39:18","slug":"maratoneti-e-non-e-tempo-di-auguri","status":"publish","type":"post","link":"https:\/\/blog.ilgiornale.it\/ruzzo\/2009\/12\/23\/maratoneti-e-non-e-tempo-di-auguri\/","title":{"rendered":"Maratoneti (e non): \u00e8 tempo di auguri"},"content":{"rendered":"<p>[photopress:SDC12624_1_2.JPG,full,alignleft]Non so chi correr\u00e0 il giorno di Natale, io probabilmente s\u00ec perch\u00e8\u00a0 prendermi una pausa tra il pranzo di mia suocera e la cena di mia madre fa ormai parte della mia tradizione natalizia. Ma a parte questa piccola divagazione personale questo vuole essere nell&#8217;intento un post di auguri di buone feste a tutti quelli che leggono questo blog. Corridori, ciclisti, triatleti, canoisti, appassionati, curiosi e avanti cos\u00ec, vale per tutti. Per farlo far\u00f2 una cosa che non si fa, cos\u00ec come ci hanno insegnato a scuola. Copio ( e incollo) la lettera di auguri che Davide, un mio compagno di canoa, ha inviato a me e ad altri temerari che a dicembre hanno solcato le acque dell&#8217;idroscalo pagaiando. Eccola qui insieme ad una foto scattata qualche settimana fa che credo renda bene l&#8217;idea della magia che viviamo ogni luned&#8217; mattina. Auguri a tutti<\/p>\n<p>Tutti noi sappiamo che la corsa ci ha consentito il miglioramento e l&#8217;aumento:<br \/>\n1) della lucidit\u00e0 mentale in quanto il nostro cervello riceve sangue pi\u00f9 ossigenato;<br \/>\n2) della memoria, creativit\u00e0 e capacit\u00e0 di apprendimento connaturate all&#8217;aumento dell&#8217;attivit\u00e0 neuronale;<br \/>\n3) dell&#8217;efficienza cardiaca che a riposo ottiene lo stesso risultato lavorando molto di meno (il minor utilizzo significa un&#8217;usura pi\u00f9 lenta);<br \/>\n4) della capacit\u00e0 immunitaria in quanto le cellule sono pi\u00f9 sensibili all&#8217;insulina e il pancreas \u00e8 meno sollecitato;<br \/>\n5) della capacit\u00e0 polmonare dovuta alla ventilazione dei polmoni che assorbono maggiori quantit\u00e0 di ossigeno e riescono ad espellere pi\u00f9 facilmente l&#8217;anidride carbonica dagli alveoli;<br \/>\n6) del desiderio sessuale, della vitalit\u00e0, libido e determinazione dovuto all&#8217;aumento del testosterone (l&#8217;ormone della virilit\u00e0);<br \/>\n7) del buon umore grazie all&#8217;innalzamento dei livelli di serotonina (i farmaci antidepressivi si basano sulla stimolazione di questo ormone della felicit\u00e0) che ha anche una funzione antiemorragica e antinfiammatoria;<br \/>\n8) della performance muscolare in quanto le cellule dei muscoli (arti inferiori e addominali bassi) diventano pi\u00f9 forti ed elastiche;<\/p>\n<p>con effetti collaterali altrettanto piacevoli:<\/p>\n<p>9) il formicolante stato di ebbrezza dovuto alla produzione di endorfine (l&#8217;altro ormone della felicit\u00e0) prodotta dal nostro corpo per aiutare a sopportare il dolore in condizioni aerobiche;<\/p>\n<p>e che l&#8217;abbiamo utilizzata per combattere:<\/p>\n<p>10) lo stress che con l&#8217;eccesso di adrenalina rende porose le pareti interne dei vasi sanguigni consentendo il deposito di calcare e grassi rendendo legnoso il sistema circolatorio si pu\u00f2 smaltire con la corsa;<br \/>\n11) virus e batteri in quanto 30 minuti di corsa aumentano del 30 per cento il numero di cellule killer (anticorpi) nel sangue;<br \/>\n12) l&#8217;insonnia, sono diversi gli studi che dimostrano che il running apporti incredibili benefici al sonno.<\/p>\n<p>A questi 12 buoni motivi per correre se ne possono sicuramente aggiungere altri, tra cui la possibilit\u00e0 di cimentarsi, tempo permettendo, in diversi sport aerobici.<\/p>\n<p>Da gennaio partir\u00e0 la nuova stagione di canoa all&#8217;Idropark e alla modica cifra di 80 euro per 6 lezioni potrete scoprire un altro sport divertente ed antiossidante.<\/p>\n<p>Auguroni a tutti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><p>[photopress:SDC12624_1_2.JPG,full,alignleft]Non so chi correr\u00e0 il giorno di Natale, io probabilmente s\u00ec perch\u00e8\u00a0 prendermi una pausa tra il pranzo di mia suocera e la cena di mia madre fa ormai parte della mia tradizione natalizia. Ma a parte questa piccola divagazione personale questo vuole essere nell&#8217;intento un post di auguri di buone feste a tutti quelli che leggono questo blog. Corridori, ciclisti, triatleti, canoisti, appassionati, curiosi e avanti cos\u00ec, vale per tutti. Per farlo far\u00f2 una cosa che non si fa, cos\u00ec come ci hanno insegnato a scuola. Copio ( e incollo) la lettera di auguri che Davide, un mio compagno [&hellip;]<\/p>\n&nbsp;&nbsp;<div class=\"readmore\"><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/2009\/12\/23\/maratoneti-e-non-e-tempo-di-auguri\/\">Continua a leggere...<\/a><\/div><\/p>","protected":false},"author":956,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/149"}],"collection":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/users\/956"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":0,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}