{"id":28417,"date":"2020-09-14T23:39:21","date_gmt":"2020-09-14T21:39:21","guid":{"rendered":"https:\/\/blog.ilgiornale.it\/ruzzo\/?p=28417"},"modified":"2020-09-14T23:39:21","modified_gmt":"2020-09-14T21:39:21","slug":"sportivi-ma-attenzione-al-sovrappeso","status":"publish","type":"post","link":"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/14\/sportivi-ma-attenzione-al-sovrappeso\/","title":{"rendered":"Sportivi ma attenzione al sovrappeso"},"content":{"rendered":"<p>Sovrappeso ma comunque capaci di buone prestazioni sportive. Si pu\u00f2 fare ma non si dovrebbe, vale per tutti ma soprattutto a una certa et\u00e0. E cos\u00ec quando gli atleti amatori sono avanti negli anni\u00a0l\u2019attenzione al peso e alla loro alimentazione deve essere maggiore. Sembra ovvio ma in realt\u00e0 non lo \u00e8 perch\u00e8 spesso chi fa sport concentra la sua attenzione sulla prestazione fisica e meno sulla sua condizione fisica. .\u00a0E\u2019 cos\u00ec \u00e8 un falso scientifico quello che gli anglosassoni chiamano \u2018\u201dfat but fit\u201d, indicando una persona grassa che tuttavia \u00e8 in grado di sostenere con buone performance uno sforzo fisico. A mettere in dubbio il concetto, lanciando un monito a chi pensa di farla franca compensando con una vita attiva gli effetti negativi dei chili di troppo sulla salute, \u00e8 uno studio svedese pubblicato sull\u2019\u00a0<strong>International Journal of Epidemiology<\/strong>. Il risultato non \u00e8\u00a0 da sottovalutare perch\u00e8 l\u2019obesit\u00e0 secondo i ricercatori svedesi\u00a0 sarebbe pi\u00f9 pericolosa della pigrizia. Essere patologicamente sovrappeso, in altre parole, cancella i benefici salvavita dello sport. Bench\u00e9 i danni della vita sedentaria siano ben documentati e reali, gli studi che analizzano l\u2019impatto di una scarsa capacit\u00e0 di sostenere sforzi aerobici riguardano soprattutto la popolazione anziana, spiegano gli autori del lavoro. Poche ricerche hanno invece analizzato il legame diretto tra fitness e salute nei giovani. Nel loro studio, quindi, gli scienziati scandinavi hanno seguito oltre 1,3 milioni di uomini in media 29enni, per esaminare l\u2019associazione tra performance fisiche e rischio di morte e valutare il \u2018peso\u2019 dell\u2019obesit\u00e0 sui risultati ottenuti. Ai partecipanti alla ricerca \u00e8 stato chiesto di pedalare fino a quando si sentivano troppo stanchi per continuare a farlo. E\u2019 emerso che gli uomini pi\u00f9 \u2018fit\u2019 hanno un rischio di morte per tutte le cause del 48% pi\u00f9 basso rispetto a quelli meno performanti.\u00a0\u00a0Passando all\u2019analisi del concetto di \u2018fat but fit\u2019, i ricercatori hanno osservato che gli uomini normopeso, indipendentemente dal livello di fitness, avevano un rischio di morte inferiore rispetto ai maschi obesi che vantavano le performance aerobiche pi\u00f9 alte. E anche se i benefici relativi di essere prestanti nell\u2019esercizio fisico possono essere maggiori nelle persone obese, gli autori concludono che \u201cin questo studio i vantaggi di un elevato fitness aerobico si riducono con l\u2019aumento del grado di obesit\u00e0, fino a scomparire negli obesi gravi\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><p>Sovrappeso ma comunque capaci di buone prestazioni sportive. Si pu\u00f2 fare ma non si dovrebbe, vale per tutti ma soprattutto a una certa et\u00e0. E cos\u00ec quando gli atleti amatori sono avanti negli anni\u00a0l\u2019attenzione al peso e alla loro alimentazione deve essere maggiore. Sembra ovvio ma in realt\u00e0 non lo \u00e8 perch\u00e8 spesso chi fa sport concentra la sua attenzione sulla prestazione fisica e meno sulla sua condizione fisica. .\u00a0E\u2019 cos\u00ec \u00e8 un falso scientifico quello che gli anglosassoni chiamano \u2018\u201dfat but fit\u201d, indicando una persona grassa che tuttavia \u00e8 in grado di sostenere con buone performance uno sforzo fisico. [&hellip;]<\/p>\n&nbsp;&nbsp;<div class=\"readmore\"><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/14\/sportivi-ma-attenzione-al-sovrappeso\/\">Continua a leggere...<\/a><\/div><\/p>","protected":false},"author":956,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28417"}],"collection":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/users\/956"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/comments?post=28417"}],"version-history":[{"count":1,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28417\/revisions"}],"predecessor-version":[{"id":28418,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28417\/revisions\/28418"}],"wp:attachment":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/media?parent=28417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/categories?post=28417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/tags?post=28417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}