{"id":28464,"date":"2020-09-21T15:25:49","date_gmt":"2020-09-21T13:25:49","guid":{"rendered":"https:\/\/blog.ilgiornale.it\/ruzzo\/?p=28464"},"modified":"2020-09-21T15:25:49","modified_gmt":"2020-09-21T13:25:49","slug":"colnago-e-la-bici-di-pogacar-bianca-non-gli-piaceva","status":"publish","type":"post","link":"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/21\/colnago-e-la-bici-di-pogacar-bianca-non-gli-piaceva\/","title":{"rendered":"Colnago e la bici di Pogacar: &#8220;Bianca non gli piaceva&#8230;&#8221;"},"content":{"rendered":"<p><strong><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/21\/colnago-e-la-bici-di-pogacar-bianca-non-gli-piaceva\/ern\/\" rel=\"attachment wp-att-28465\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-28465\" src=\"https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/ern-205x300.jpg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/ern-205x300.jpg 205w, https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/ern.jpg 401w\" sizes=\"(max-width: 205px) 100vw, 205px\" \/><\/a>Ernesto Colnago<\/strong> gliel&#8217;aveva mandata tutta bianca la bici per sfilare sugli Champs-Elys\u00e8es. Bianca perch\u00e9 di bianco si veste al Tour il giovane che arriva primo a Parigi. Ma<strong> Tadej Pogacar<\/strong> aveva altre idee per la testa. &#8220;Quando gliel&#8217;hanno consegnata, l&#8217;ha guardata ma non era per niente convinto &#8211; racconta Colnago &#8211; Cos\u00ec uno dei miei collaboratori mi ha telefonato subito e mi ha detto &#8220;Ernesto, guarda che al <em>fieu<\/em> la bici non piace. Non gli piace il colore&#8230;.&#8221;<\/p>\n<p><strong>Colnago \u00e8 un uomo veloce.<\/strong> Sempre stato veloce anche quando rischi\u00f2 l&#8217;arresto in Spagna per andare a portare una sua bici a re Juan Carlos o quando, in una notte, fece due volte avanti indietro dal Vaticano per cambiare una bici da corsa a papa Wojtyla che ne voleva una da passeggio. Cos\u00ec ha capito al volo che di bici per il 21enne sloveno di Komenda avrebbe dovuto farne un&#8217;altra. E senza perdere troppo tempo perch\u00e9 la cronometro che avrebbe deciso il Tour de France numero 107 era alle porte e poteva riservare qualche sorpresa: \u00abHo chiamato subito un paio di miei tecnici, ho riaperto l&#8217;azienda e ci siamo messi al lavoro &#8211; racconta &#8211; In una sera abbiamo assemblato un telaio delle misure di Pogacar e l&#8217;abbiamo verniciato di giallo. Senza dir niente a nessuno perch\u00e9 io sono scaramantico. Per\u00f2 l&#8217;ho tenuto l\u00ec, pronto. Me la sentivo&#8230;\u00bb.<\/p>\n<p><strong>Il resto \u00e8 gi\u00e0 storia.<\/strong> Tadej Pogacar sulle rampe della Planche des Belles Filles schianta le resistenze del suo connazionale Primoz Roglic che alza bandiera bianca: \u00abHo visto la cronometro in tv &#8211; racconta Colnago &#8211; Ho capito subito che il <em>&#8220;fieu&#8221;<\/em> avrebbe preso la maglia gialla quando \u00e8 iniziata la salita. Guardavo lui che pedalava rotondo spingendo un rapporto che faceva velocit\u00e0 e poi guardavo Roglic che in punta di sella pedalava troppo agile e sembrava fermo. Ho fatto fatica a non emozionarmi. Avevo gi\u00e0 capito e l&#8217;avevo gi\u00e0 detto anche a Saronnni che quel ragazzo era un fenomeno&#8230;\u00bb.<\/p>\n<p><strong>Ottant&#8217;otto anni che si sono fermati a settanta.<\/strong> Ottant&#8217;otto anni lavorando sodo, perch\u00e9 una volta era tutto pi\u00f9 difficile di adesso, perch\u00e9 una volta la vita bisognava guadagnarsela un po&#8217; pi\u00f9 di oggi. Perch\u00e9 una volta era una volta e oggi \u00e8 un altro mondo in cui per\u00f2 l&#8217;Ernesto continua a scrivere la sua storia. Cominciata in una piccola officina di 25 metri quadrati al numero 10 di via Garibaldi a Cambiago. L&#8217;Antonio e l&#8217;Elvira, i suoi genitori, volevano che continuasse a fare il contadino perch\u00e9 la terra c&#8217;era, rendeva e un paio di braccia in pi\u00f9 facevano comodo, ma l&#8217;Ernesto lo sapeva che sarebbe finita come \u00e8 finita.<\/p>\n<p><strong>Pi\u00f9 di ottomila vittorie,<\/strong> campionati del mondo, Giri d&#8217;Italia, il record dell&#8217;ora di Merckx nel 1972 a Citt\u00e0 del Messico, campioni come Magni, Nencini, Motta, Saronni, Bugno, Freire, Museeuw, Rominger, Tonkov, Zabel, Ballerini e Petacchi. Ed ora il Tour, sul gradino pi\u00f9 alto del podio con una sua bici. Ed ora questo ragazzino sloveno con l&#8217;aria sbarazzina che a 21 anni pare un predestinato: \u00abL&#8217;altra sera una delle prime chiamate che ho ricevuto \u00e8 stata quella di Eddy Merckx- racconta- Gli ho detto Eddy guarda che quel fieu l\u00ec \u00e8 il tuo erede. Mi sembra di vedere te in bicicletta. Mi ha fatto tornare giovane&#8230;\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><p>Ernesto Colnago gliel&#8217;aveva mandata tutta bianca la bici per sfilare sugli Champs-Elys\u00e8es. Bianca perch\u00e9 di bianco si veste al Tour il giovane che arriva primo a Parigi. Ma Tadej Pogacar aveva altre idee per la testa. &#8220;Quando gliel&#8217;hanno consegnata, l&#8217;ha guardata ma non era per niente convinto &#8211; racconta Colnago &#8211; Cos\u00ec uno dei miei collaboratori mi ha telefonato subito e mi ha detto &#8220;Ernesto, guarda che al fieu la bici non piace. Non gli piace il colore&#8230;.&#8221; Colnago \u00e8 un uomo veloce. Sempre stato veloce anche quando rischi\u00f2 l&#8217;arresto in Spagna per andare a portare una sua bici a [&hellip;]<\/p>\n&nbsp;&nbsp;<div class=\"readmore\"><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/21\/colnago-e-la-bici-di-pogacar-bianca-non-gli-piaceva\/\">Continua a leggere...<\/a><\/div><\/p>","protected":false},"author":956,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28464"}],"collection":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/users\/956"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/comments?post=28464"}],"version-history":[{"count":2,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28464\/revisions"}],"predecessor-version":[{"id":28467,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28464\/revisions\/28467"}],"wp:attachment":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/media?parent=28464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/categories?post=28464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/tags?post=28464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}