{"id":28478,"date":"2020-09-24T16:38:12","date_gmt":"2020-09-24T14:38:12","guid":{"rendered":"https:\/\/blog.ilgiornale.it\/ruzzo\/?p=28478"},"modified":"2020-09-24T16:38:12","modified_gmt":"2020-09-24T14:38:12","slug":"elbaman-riaprono-le-iscrizioni","status":"publish","type":"post","link":"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/24\/elbaman-riaprono-le-iscrizioni\/","title":{"rendered":"Elbaman, riaprono le iscrizioni"},"content":{"rendered":"<p style=\"font-weight: 400\"><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/eventi_sportivi-originale-0.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-28479\" src=\"https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/eventi_sportivi-originale-0-300x129.jpg\" alt=\"\" width=\"300\" height=\"129\" srcset=\"https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/eventi_sportivi-originale-0-300x129.jpg 300w, https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/eventi_sportivi-originale-0-768x330.jpg 768w, https:\/\/blog.ilgiornale.it\/ruzzo\/files\/2020\/09\/eventi_sportivi-originale-0.jpg 976w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Era l&#8217;11 giugno quando, con un videomessaggio sulla bacheca Facebook di Elbaman, l&#8217;organizzatore <strong>Marco Scotti<\/strong> annunciava che, per il\u00a0 Covid e per la situazione dei contagi che non prometteva nulla di buono, l&#8217;edizione 2020 di uno dei triathlon lunghi pi\u00f9 spettacolari in circolazione veniva cancellata: &#8220;Purtroppo questo \u00e8 un anno maledetto- spiegava Scotti- e\u00a0 con grandissimo dispiacere ci vediamo costretti a prendere questa decisione&#8230;&#8221;. Decisione saggia,\u00a0 onesta e coraggiosa come sanno essere le decisioni schiette e di buon senso. Decisione che ha evitato di alimentare inutile attese e che ha preservato il senso di una sfida unica nella sua particolarit\u00e0 e nella sua tradizione e che, alla luce delle normative di sicurezza e distanziamento che sono arrivate poi, avrebbe rischiato di snaturarsi e di diventare un&#8217;altra cosa. Ora si prova a ripartire. A qualche mese di distanza si spera che la prossima possa essere la stagione di un lento ritorno alla normalit\u00e0 o quantomeno si spera di non dover far pi\u00f9 i conti con una situazione di emergenza. Cos\u00ec luned\u00ec 28\u00a0 alle ore 10.00, come preannunciato dagli organizzatori che hanno fissato la data di Elbaman il 26 settembre 2021, prenderanno il via le iscrizioni per la XVI edizione di Elbaman. Nonostante pi\u00f9 del 40 per cento dei posti siano prenotati dagli atleti iscritti lo scorso anno, ci saranno comunque quote scaglionate per offrire agli atleti che si iscriveranno per primi, un ulteriore vantaggio.\u00a0 &#8220;Siamo dei combattenti e con tutto il nostro staff lavoreremo perch\u00e8 la prossima edizione possa essere ancora pi\u00f9 speciale- aveva promesso Scotti nel giorno in cui aveva deciso responsabilmente di fermarsi- Certo \u00e8 che noi nel 2021 ci saremo&#8230;&#8221;. E ogni promessa \u00e8 debito.<\/p>\n<p style=\"font-weight: 400\"><strong>Tutte le informazioni riguardo\u00a0 le iscrizioni si possono trovare sul nuovo sito\u00a0<a href=\"http:\/\/www.elbaman.it\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.elbaman.it&amp;source=gmail&amp;ust=1601042664894000&amp;usg=AFQjCNHPrI-tFdqa109PpEJP-udOiLotRA\">www.elbaman.it.\u00a0<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><p>Era l&#8217;11 giugno quando, con un videomessaggio sulla bacheca Facebook di Elbaman, l&#8217;organizzatore Marco Scotti annunciava che, per il\u00a0 Covid e per la situazione dei contagi che non prometteva nulla di buono, l&#8217;edizione 2020 di uno dei triathlon lunghi pi\u00f9 spettacolari in circolazione veniva cancellata: &#8220;Purtroppo questo \u00e8 un anno maledetto- spiegava Scotti- e\u00a0 con grandissimo dispiacere ci vediamo costretti a prendere questa decisione&#8230;&#8221;. Decisione saggia,\u00a0 onesta e coraggiosa come sanno essere le decisioni schiette e di buon senso. Decisione che ha evitato di alimentare inutile attese e che ha preservato il senso di una sfida unica nella sua particolarit\u00e0 [&hellip;]<\/p>\n&nbsp;&nbsp;<div class=\"readmore\"><a href=\"https:\/\/blog.ilgiornale.it\/ruzzo\/2020\/09\/24\/elbaman-riaprono-le-iscrizioni\/\">Continua a leggere...<\/a><\/div><\/p>","protected":false},"author":956,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28478"}],"collection":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/users\/956"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/comments?post=28478"}],"version-history":[{"count":1,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28478\/revisions"}],"predecessor-version":[{"id":28480,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/posts\/28478\/revisions\/28480"}],"wp:attachment":[{"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/media?parent=28478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/categories?post=28478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ilgiornale.it\/ruzzo\/wp-json\/wp\/v2\/tags?post=28478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}